{"id":154631,"date":"2025-02-20T08:01:33","date_gmt":"2025-02-20T07:01:33","guid":{"rendered":"https:\/\/www.greisinger.com\/?post_type=produkte&#038;p=154631"},"modified":"2025-02-20T08:01:34","modified_gmt":"2025-02-20T07:01:34","slug":"muehlviertler-schinkenspeck-ohne-schwarte-1800g-2","status":"publish","type":"produkte","link":"https:\/\/www.greisinger.com\/en\/produkte\/muehlviertler-schinkenspeck-ohne-schwarte-1800g-2\/","title":{"rendered":"M\u00fchlviertler Schinkenspeck ohne Schwarte 1800g"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":9937,"template":"","product_category":[313,242],"class_list":["post-154631","produkte","type-produkte","status-publish","has-post-thumbnail","hentry","product_category-raucherspezialitaten","product_category-export"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00fchlviertler Schinkenspeck ohne Schwarte 1800g - Greisinger GmbH - Fleisch-, Wurst- und Selchwaren<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.greisinger.com\/en\/produkte\/muehlviertler-schinkenspeck-ohne-schwarte-1800g-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00fchlviertler Schinkenspeck ohne Schwarte 1800g - Greisinger GmbH - Fleisch-, Wurst- und Selchwaren\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.greisinger.com\/en\/produkte\/muehlviertler-schinkenspeck-ohne-schwarte-1800g-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Greisinger GmbH - Fleisch-, Wurst- und Selchwaren\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-20T07:01:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.greisinger.com\/wp-content\/uploads\/2022\/06\/26562_SchinkenspeckoS_ret_WEB.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.greisinger.com\\\/en\\\/produkte\\\/muehlviertler-schinkenspeck-ohne-schwarte-1800g-2\\\/\",\"url\":\"https:\\\/\\\/www.greisinger.com\\\/en\\\/produkte\\\/muehlviertler-schinkenspeck-ohne-schwarte-1800g-2\\\/\",\"name\":\"M\u00fchlviertler Schinkenspeck ohne Schwarte 1800g - Greisinger GmbH - Fleisch-, Wurst- und Selchwaren\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.greisinger.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.greisinger.com\\\/en\\\/produkte\\\/muehlviertler-schinkenspeck-ohne-schwarte-1800g-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.greisinger.com\\\/en\\\/produkte\\\/muehlviertler-schinkenspeck-ohne-schwarte-1800g-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.greisinger.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/26562_SchinkenspeckoS_ret_WEB.jpg\",\"datePublished\":\"2025-02-20T07:01:33+00:00\",\"dateModified\":\"2025-02-20T07:01:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.greisinger.com\\\/en\\\/produkte\\\/muehlviertler-schinkenspeck-ohne-schwarte-1800g-2\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.greisinger.com\\\/en\\\/produkte\\\/muehlviertler-schinkenspeck-ohne-schwarte-1800g-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.greisinger.com\\\/en\\\/produkte\\\/muehlviertler-schinkenspeck-ohne-schwarte-1800g-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.greisinger.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/26562_SchinkenspeckoS_ret_WEB.jpg\",\"contentUrl\":\"https:\\\/\\\/www.greisinger.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/26562_SchinkenspeckoS_ret_WEB.jpg\",\"width\":1920,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.greisinger.com\\\/en\\\/produkte\\\/muehlviertler-schinkenspeck-ohne-schwarte-1800g-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.greisinger.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00fchlviertler Schinkenspeck ohne Schwarte 1800g\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.greisinger.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.greisinger.com\\\/en\\\/\",\"name\":\"Greisinger GmbH - Fleisch-, Wurst- und Selchwaren\",\"description\":\"Greisinger, ein rein privat gef\u00fchrtes Top-Fleischverarbeitungsunternehmen aus \u00d6sterreich stellt Fleisch- und Wurst-, Salami- und Snack-Produkte h\u00f6chster Qualit\u00e4t her \u2013 f\u00fcr Kunden aus \u00fcber 40 L\u00e4ndern weltweit.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.greisinger.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.greisinger.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.greisinger.com\\\/en\\\/#organization\",\"name\":\"Greisinger GmbH - Fleisch-, Wurst- und Selchwaren\",\"url\":\"https:\\\/\\\/www.greisinger.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.greisinger.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.greisinger.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo_greisinger.png\",\"contentUrl\":\"https:\\\/\\\/www.greisinger.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo_greisinger.png\",\"width\":200,\"height\":200,\"caption\":\"Greisinger GmbH - Fleisch-, Wurst- und Selchwaren\"},\"image\":{\"@id\":\"https:\\\/\\\/www.greisinger.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00fchlviertler Schinkenspeck ohne Schwarte 1800g - Greisinger GmbH - Fleisch-, Wurst- und Selchwaren","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.greisinger.com\/en\/produkte\/muehlviertler-schinkenspeck-ohne-schwarte-1800g-2\/","og_locale":"en_GB","og_type":"article","og_title":"M\u00fchlviertler Schinkenspeck ohne Schwarte 1800g - Greisinger GmbH - Fleisch-, Wurst- und Selchwaren","og_url":"https:\/\/www.greisinger.com\/en\/produkte\/muehlviertler-schinkenspeck-ohne-schwarte-1800g-2\/","og_site_name":"Greisinger GmbH - Fleisch-, Wurst- und Selchwaren","article_modified_time":"2025-02-20T07:01:34+00:00","og_image":[{"width":1920,"height":1440,"url":"https:\/\/www.greisinger.com\/wp-content\/uploads\/2022\/06\/26562_SchinkenspeckoS_ret_WEB.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.greisinger.com\/en\/produkte\/muehlviertler-schinkenspeck-ohne-schwarte-1800g-2\/","url":"https:\/\/www.greisinger.com\/en\/produkte\/muehlviertler-schinkenspeck-ohne-schwarte-1800g-2\/","name":"M\u00fchlviertler Schinkenspeck ohne Schwarte 1800g - Greisinger GmbH - Fleisch-, Wurst- und Selchwaren","isPartOf":{"@id":"https:\/\/www.greisinger.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.greisinger.com\/en\/produkte\/muehlviertler-schinkenspeck-ohne-schwarte-1800g-2\/#primaryimage"},"image":{"@id":"https:\/\/www.greisinger.com\/en\/produkte\/muehlviertler-schinkenspeck-ohne-schwarte-1800g-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.greisinger.com\/wp-content\/uploads\/2022\/06\/26562_SchinkenspeckoS_ret_WEB.jpg","datePublished":"2025-02-20T07:01:33+00:00","dateModified":"2025-02-20T07:01:34+00:00","breadcrumb":{"@id":"https:\/\/www.greisinger.com\/en\/produkte\/muehlviertler-schinkenspeck-ohne-schwarte-1800g-2\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.greisinger.com\/en\/produkte\/muehlviertler-schinkenspeck-ohne-schwarte-1800g-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.greisinger.com\/en\/produkte\/muehlviertler-schinkenspeck-ohne-schwarte-1800g-2\/#primaryimage","url":"https:\/\/www.greisinger.com\/wp-content\/uploads\/2022\/06\/26562_SchinkenspeckoS_ret_WEB.jpg","contentUrl":"https:\/\/www.greisinger.com\/wp-content\/uploads\/2022\/06\/26562_SchinkenspeckoS_ret_WEB.jpg","width":1920,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/www.greisinger.com\/en\/produkte\/muehlviertler-schinkenspeck-ohne-schwarte-1800g-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.greisinger.com\/en\/"},{"@type":"ListItem","position":2,"name":"M\u00fchlviertler Schinkenspeck ohne Schwarte 1800g"}]},{"@type":"WebSite","@id":"https:\/\/www.greisinger.com\/en\/#website","url":"https:\/\/www.greisinger.com\/en\/","name":"Greisinger GmbH - Fleisch-, Wurst- und Selchwaren","description":"Greisinger, ein rein privat gef\u00fchrtes Top-Fleischverarbeitungsunternehmen aus \u00d6sterreich stellt Fleisch- und Wurst-, Salami- und Snack-Produkte h\u00f6chster Qualit\u00e4t her \u2013 f\u00fcr Kunden aus \u00fcber 40 L\u00e4ndern weltweit.","publisher":{"@id":"https:\/\/www.greisinger.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.greisinger.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.greisinger.com\/en\/#organization","name":"Greisinger GmbH - Fleisch-, Wurst- und Selchwaren","url":"https:\/\/www.greisinger.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.greisinger.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.greisinger.com\/wp-content\/uploads\/2022\/01\/logo_greisinger.png","contentUrl":"https:\/\/www.greisinger.com\/wp-content\/uploads\/2022\/01\/logo_greisinger.png","width":200,"height":200,"caption":"Greisinger GmbH - Fleisch-, Wurst- und Selchwaren"},"image":{"@id":"https:\/\/www.greisinger.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.greisinger.com\/en\/wp-json\/wp\/v2\/produkte\/154631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.greisinger.com\/en\/wp-json\/wp\/v2\/produkte"}],"about":[{"href":"https:\/\/www.greisinger.com\/en\/wp-json\/wp\/v2\/types\/produkte"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.greisinger.com\/en\/wp-json\/wp\/v2\/media\/9937"}],"wp:attachment":[{"href":"https:\/\/www.greisinger.com\/en\/wp-json\/wp\/v2\/media?parent=154631"}],"wp:term":[{"taxonomy":"product_category","embeddable":true,"href":"https:\/\/www.greisinger.com\/en\/wp-json\/wp\/v2\/product_category?post=154631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}